{"id":324,"date":"2026-08-31T10:10:32","date_gmt":"2026-08-31T10:10:32","guid":{"rendered":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/?page_id=324"},"modified":"2026-08-31T10:15:29","modified_gmt":"2026-08-31T10:15:29","slug":"faq","status":"publish","type":"page","link":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"324\" class=\"elementor elementor-324\" data-elementor-settings=\"{&quot;ha_cmc_init_switcher&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94a208a e-flex e-con-boxed e-con e-parent\" data-id=\"94a208a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bd68968 elementor-widget elementor-widget-page-title\" data-id=\"bd68968\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"page-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\n\t\t<div class=\"hfe-page-title hfe-page-title-wrapper elementor-widget-heading\">\n\n\t\t\t\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\n\t\t\t\t\t\t\t\t\n\t\t\t\tFAQ  \n\t\t\t<\/h2 > \n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5208227 elementor-widget elementor-widget-hfe-breadcrumbs-widget\" data-id=\"5208227\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"hfe-breadcrumbs-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<nav aria-label=\"Breadcrumb\"><ul class=\"hfe-breadcrumbs hfe-breadcrumbs-show-home\"><li class=\"hfe-breadcrumbs-item hfe-breadcrumbs-first\"><span class=\"hfe-breadcrumbs-home-icon\"><\/span><a href=\"https:\/\/preview.wpelemento.com\/industrial-services-elementor\"><span class=\"hfe-breadcrumbs-text\">Home<\/span><\/a><\/li><\/ul><\/nav>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-174cac5f e-flex e-con-boxed e-con e-parent\" data-id=\"174cac5f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ha_eqh_enable&quot;:false}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74a66c4f elementor-widget elementor-widget-elementskit-accordion\" data-id=\"74a66c4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a97af0c1c2b2\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-74a66c4f\">\n                        <a href=\"#collapse-f9574066a97af0c1c2b2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f9574066a97af0c1c2b2\" aria-expanded=\"true\" aria-controls=\"Collapse-f9574066a97af0c1c2b2\">\n                            \n                            <span class=\"ekit-accordion-title\">How to Change my Photo from Admin Dashboard?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f9574066a97af0c1c2b2\" class=\" show collapse\" aria-labelledby=\"primaryHeading-0-74a66c4f\" data-parent=\"#accordion-6a97af0c1c2b2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-74a66c4f\">\n                        <a href=\"#collapse-9fa44826a97af0c1c2b2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9fa44826a97af0c1c2b2\" aria-expanded=\"false\" aria-controls=\"Collapse-9fa44826a97af0c1c2b2\">\n                            \n                            <span class=\"ekit-accordion-title\">How to Change my Password easily?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9fa44826a97af0c1c2b2\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-74a66c4f\" data-parent=\"#accordion-6a97af0c1c2b2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-74a66c4f\">\n                        <a href=\"#collapse-32db88a6a97af0c1c2b2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-32db88a6a97af0c1c2b2\" aria-expanded=\"false\" aria-controls=\"Collapse-32db88a6a97af0c1c2b2\">\n                            \n                            <span class=\"ekit-accordion-title\">How to Change my Subscription Plan using PayPal<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-32db88a6a97af0c1c2b2\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-74a66c4f\" data-parent=\"#accordion-6a97af0c1c2b2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-74a66c4f\">\n                        <a href=\"#collapse-b4ad5436a97af0c1c2b2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-b4ad5436a97af0c1c2b2\" aria-expanded=\"false\" aria-controls=\"Collapse-b4ad5436a97af0c1c2b2\">\n                            \n                            <span class=\"ekit-accordion-title\">Know About Why We Are Best In The Industry!<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-b4ad5436a97af0c1c2b2\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-74a66c4f\" data-parent=\"#accordion-6a97af0c1c2b2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-74a66c4f\">\n                        <a href=\"#collapse-6b0da7d6a97af0c1c2b2\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-6b0da7d6a97af0c1c2b2\" aria-expanded=\"false\" aria-controls=\"Collapse-6b0da7d6a97af0c1c2b2\">\n                            \n                            <span class=\"ekit-accordion-title\">Energy Efficiency Solutions for Industrial Plants<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"icon icon-up-arrow\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-6b0da7d6a97af0c1c2b2\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-74a66c4f\" data-parent=\"#accordion-6a97af0c1c2b2\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>FAQ Home How to Change my Photo from Admin Dashboard? Far far away, behind the word mountains, far from the countries Vokalia and Consonantia, there live the blind texts. Separated they live in Bookmarksgrove right at the coast How to Change my Password easily? Far far away, behind the word mountains, far from the countries [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-324","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/wp-json\/wp\/v2\/pages\/324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/wp-json\/wp\/v2\/comments?post=324"}],"version-history":[{"count":7,"href":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/wp-json\/wp\/v2\/pages\/324\/revisions"}],"predecessor-version":[{"id":339,"href":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/wp-json\/wp\/v2\/pages\/324\/revisions\/339"}],"wp:attachment":[{"href":"https:\/\/preview.wpelemento.com\/industrial-services-elementor\/wp-json\/wp\/v2\/media?parent=324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}